{"id":15,"date":"2026-04-15T22:26:01","date_gmt":"2026-04-15T22:26:01","guid":{"rendered":"https:\/\/spidersport.at\/restaurations\/links\/"},"modified":"2026-04-15T22:26:01","modified_gmt":"2026-04-15T22:26:01","slug":"links","status":"publish","type":"page","link":"https:\/\/spidersport.at\/restaurations\/links\/","title":{"rendered":"Links"},"content":{"rendered":"<p>Hier finden Sie ausgew\u00e4hlte Verweise rund um klassische Alfa Romeo, italienische Fahrzeuge und Teileversorgung.<\/p>\n<ul>\n<li><a href=\"http:\/\/www.alfaclub.cc\/\" target=\"_blank\" rel=\"noopener\">www.alfaclub.cc<\/a> \u2013 Club f\u00fcr Oldtimer, Youngtimer und die \u201eNew Generation\u201c der Marke Alfa Romeo<\/li>\n<li><a href=\"http:\/\/www.need4speed.at\/\" target=\"_blank\" rel=\"noopener\">www.need4speed.at<\/a> \u2013 Faszination Geschwindigkeit hat einen Namen<\/li>\n<li><a href=\"http:\/\/www.alfa-fiat-spidersport.at\/links\/\" target=\"_blank\" rel=\"noopener\">www.alfa-fiat-spidersport.at<\/a> \u2013 Ersatzteilhandel f\u00fcr klassische Fahrzeuge der Marken Alfa Romeo, Fiat und Lancia<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Hier finden Sie ausgew\u00e4hlte Verweise rund um klassische Alfa Romeo, italienische Fahrzeuge und Teileversorgung. www.alfaclub.cc \u2013 Club f\u00fcr Oldtimer, Youngtimer und die \u201eNew Generation\u201c der Marke Alfa Romeo www.need4speed.at \u2013 Faszination Geschwindigkeit hat einen Namen www.alfa-fiat-spidersport.at \u2013 Ersatzteilhandel f\u00fcr klassische Fahrzeuge der Marken Alfa Romeo, Fiat und Lancia<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":0,"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"wp:attachment":[{"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}