{"id":14,"date":"2026-04-15T22:26:01","date_gmt":"2026-04-15T22:26:01","guid":{"rendered":"https:\/\/spidersport.at\/restaurations\/innenausstattung\/sitze\/"},"modified":"2026-04-15T22:26:01","modified_gmt":"2026-04-15T22:26:01","slug":"sitze","status":"publish","type":"page","link":"https:\/\/spidersport.at\/restaurations\/innenausstattung\/sitze\/","title":{"rendered":"Sitze"},"content":{"rendered":"<p>Neuaufbau und Aufarbeitung von Sitzen und Innenausstattung \u2013 mit einem Auge f\u00fcr Originaloptik, Sitzkomfort und wertige Haptik.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neuaufbau und Aufarbeitung von Sitzen und Innenausstattung \u2013 mit einem Auge f\u00fcr Originaloptik, Sitzkomfort und wertige Haptik.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":12,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":0,"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/pages\/12"}],"wp:attachment":[{"href":"https:\/\/spidersport.at\/restaurations\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}